{"id":556,"date":"2018-07-14T03:25:58","date_gmt":"2018-07-14T03:25:58","guid":{"rendered":"http:\/\/dgk.e48.mytemp.website\/?p=556"},"modified":"2026-06-28T03:37:11","modified_gmt":"2026-06-28T03:37:11","slug":"james-bond-oltre","status":"publish","type":"post","link":"https:\/\/pandaphukettour.com\/it\/james-bond-beyond\/","title":{"rendered":"JAMES BOND SAMET PHANG NGA BAY \ud83c\uddee\ud83c\uddf9 IN GRUPPO, PARTENZA ANTICIPATA IN ITALIANO IN MOTOSCAFO"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;556&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;384&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.9&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.9\\\/5&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;JAMES BOND SAMET PHANG NGA BAY \ud83c\uddea\ud83c\uddf8 EN GRUPO, SALIDA TEMPRANA EN ESPA\u00d1OL EN LANCHA MOTORA&quot;,&quot;width&quot;:&quot;139.6&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best}&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 139.6px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            4.9\/5    <\/div>\n    <\/div>\n[et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||8px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb8px||9px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAnton||||||||\u00bb text_font_size=\u00bb16px\u00bb text_letter_spacing=\u00bb5px\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]\n<p>TRAVEL PRODUCT ID: 1 &#8211; 1011<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb3px||1px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAnton||||||||\u00bb text_text_color=\u00bb#ea7d00&#8243; text_font_size=\u00bb21px\u00bb text_line_height=\u00bb1.6em\u00bb header_font=\u00bbAnton|||on|||||\u00bb header_text_color=\u00bb#00d3d0&#8243; header_font_size=\u00bb28px\u00bb header_letter_spacing=\u00bb2px\u00bb header_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb|-13px||-12px||\u00bb header_text_shadow_style=\u00bbpreset1&#8243; header_text_shadow_vertical_length=\u00bb0.02em\u00bb header_text_shadow_blur_strength=\u00bb0.03em\u00bb header_text_shadow_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]\n<h1><span style=\"color: #19dd19;\">James Bond and Beyond Phang Nga Bay EN GRUPO &#8211; SALIDA TEMPRANA EN ESPA\u00d1OL (M\u00e1ximo 32 personas)<\/span><\/h1>\n<h2>El Mirador de Samet: Exclusivo en la Salida Temprana<\/h2>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-Beyond-Background.jpg\u00bb title_text=\u00bbJames Bond Beyond Background\u00bb disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb4px||9px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb19px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb15px\u00bb text_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\" style=\"text-align: center;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\" style=\"color: #13ba13;\"><span style=\"font-size: x-large;\"><strong>PICK UP TIME<\/strong><\/span><\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\" style=\"text-align: center;\"><span style=\"color: #179bbd; font-family: Alata; font-size: medium;\"><span style=\"color: #28b56e;\"><strong><span style=\"color: #808080;\"><span style=\"color: #e84c09;\">\u23f1<\/span><\/span><\/strong><\/span><\/span><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">05:00-06:00 AM:<\/span> Te recogeremos en tu hotel y te llevaremos al <span style=\"color: #19dd19;\">Royal Phuket Marina.<\/span><\/span><\/p>\n<p><span style=\"font-size: medium;\"><span style=\"color: #179bbd; font-family: Alata; font-size: medium;\"><span style=\"color: #28b56e;\"><strong><span style=\"color: #808080;\"><span style=\"color: #e84c09;\">\u23f1<\/span><\/span><\/strong><\/span><\/span><span style=\"color: #19dd19;\">06:40-07:00 AM: <\/span>Salida temprana hacia la <span style=\"color: #19dd19;\">Bah\u00eda de Phang Nga.<\/span> Rel\u00e1jate en nuestro c\u00f3modo speedboat mientras nos embarcamos en nuestra aventura para explorar las fascinantes islas y lugares de inter\u00e9s.<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\" style=\"text-align: left;\">[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb10px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAnton||||||||\u00bb text_text_color=\u00bb#00d3d0&#8243; text_font_size=\u00bb29px\u00bb text_letter_spacing=\u00bb6px\u00bb text_orientation=\u00bbcenter\u00bb text_text_shadow_style=\u00bbpreset1&#8243; text_text_shadow_vertical_length=\u00bb0.03em\u00bb text_text_shadow_blur_strength=\u00bb0.01em\u00bb text_text_shadow_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]\n<p><span style=\"color: #19dd19;\">PHANG NGA BAY\u00a0<\/span><\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb background_enable_image=\u00bboff\u00bb min_height=\u00bb349px\u00bb custom_padding=\u00bb3px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb1px||3px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-007-en-Tailandia-jpg.webp\u00bb alt=\u00bbelephant\u00bb title_text=\u00bbJames Bond 007 en Tailandia\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb15px\u00bb custom_margin=\u00bb16px|||||\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">Emb\u00e1rcate en una aventura inolvidable mientras exploramos la ic\u00f3nica <span style=\"color: #19dd19;\">Isla James Bond<\/span> y sus hermosos alrededores. Desde visitar la famosa isla destacada en <span style=\"color: #19dd19;\">\u00ab007 El hombre de la pistola de oro\u00bb<\/span> hasta remar en canoa a trav\u00e9s de manglares y cuevas, este tour de madrugada est\u00e1 repleto de actividades emocionantes y paisajes impresionantes. Experimenta la belleza impresionante de la <span style=\"color: #19dd19;\">Bah\u00eda de Phang Nga<\/span> y sus cautivadoras islas en este emocionante viaje.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">*ITINERARIO:<\/span> *Nos reservamos el derecho de modificar o alterar la ruta planificada seg\u00fan fluctuaciones en patrones clim\u00e1ticos, variaciones de mareas, condiciones oce\u00e1nicas o cualquier situaci\u00f3n impredecible.<\/span><\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb6px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/Phang-Nga-Bay-jpg.webp\u00bb title_text=\u00bbPhang Nga Bay\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px|||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||3px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<ul>\n<li>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">KOH PANAK<\/span> Visita desde el barco Koh Panak, una isla impresionante con caracter\u00edsticas geol\u00f3gicas \u00fanicas. Explora el cautivador paisaje de la isla y marav\u00edllate con su belleza natural. <\/span><\/p>\n<\/li>\n<li>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">TOUR POR LA CUEVA A PIE<\/span> Luego, emprenderemos un tour a pie por cuevas. Ad\u00e9ntrate en las profundidades de estas cuevas encantadas y sorpr\u00e9ndete con las formaciones incre\u00edbles que hay dentro.<\/span><\/p>\n<\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb0px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-007-Isla-jpg.webp\u00bb alt=\u00bbelephant\u00bb title_text=\u00bbJames Bond 007 Isla\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||8px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<ul>\n<li>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">ISLA JAMES BOND<\/span> Luego visitaremos la famosa Isla James Bond, el lugar de rodaje de <span style=\"color: #19dd19;\">\u00ab007 El hombre de la pistola de oro\u00bb.<\/span> Explora la ic\u00f3nica isla y toma fotos inolvidables con los distintivos acantilados de piedra caliza y formaciones rocosas<\/span><\/p>\n<\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb0px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/Canoeing-en-Phang-Nga-Desde-Phuket-jpg.webp\u00bb alt=\u00bbelephant\u00bb title_text=\u00bbCanoeing en Phang Nga Desde Phuket\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb2px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb custom_margin=\u00bb19px|||||\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]\n<ul>\n<li style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">CANOA EN TUM LOD<\/span> Vive una relajante aventura en canoa a trav\u00e9s de los manglares y cuevas de <span style=\"color: #19dd19;\">Tum Lod.<\/span> Rema en las serenas aguas y contempla la impresionante belleza natural que te rodea.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb0px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/Panyee-Village-Flotante-en-Phang-Nga-jpg.webp\u00bb alt=\u00bbelephant\u00bb title_text=\u00bbPanyee Village Flotante en Phang Nga\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb8px|||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||15px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<ul>\n<li>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">KOH PANYEE DESDE EL BARCO<\/span> Mientras continuamos nuestro recorrido, pasaremos por la zona del restaurante frontal de<span style=\"color: #19dd19;\"> Koh Panyee<\/span>, un pueblo flotante \u00fanico construido sobre pilotes sobre el agua. Disfruta del avistamiento desde el barco y contempla la fascinante arquitectura de este notable pueblo.<\/span><\/p>\n<\/li>\n<li style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">PASEO POR KOH PANYEE EN EL PUEBLO FLOTANTE<\/span> Visita <span style=\"color: #19dd19;\">Koh Panyee<\/span> y camina por el pueblo flotante, donde podr\u00e1s explorar el estilo de vida local y vivir la vibrante cultura.<\/span><\/li>\n<li>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">ALMUERZO BUFFET TAILAND\u00c9S EN LA ISLA<\/span> Disfruta de un delicioso almuerzo en un restaurante local en la isla de Panyee (New Fern). Saborea aut\u00e9nticos sabores locales mientras contemplas las impresionantes vistas de la isla.<\/span><\/p>\n<\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb0px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/Phang-Nga-Bay-Desde-Phuket-jpg.webp\u00bb alt=\u00bbelephant\u00bb title_text=\u00bbPhang Nga Bay Desde Phuket\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb4px||1px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb custom_margin=\u00bb20px|||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<ul>\n<ul>\n<li style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">VISTA DE LA BAH\u00cdA DE PHANG NGA NUEVO!!!<\/span> Disfruta de la vista desde el punto de vista de <span style=\"color: #19dd19;\">Samet Nangshe.<\/span><\/span><\/li>\n<li style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">REL\u00c1JATE Y TOMA EL SOL EN UNA PLAYA TROPICAL<\/span> Termina el d\u00eda relaj\u00e1ndote y tomando el sol en una playa tropical, sum\u00e9rgete en la suave arena rodeada de aguas esmeralda. Luego regresaremos al Royal Phuket Marina para tu traslado de vuelta al hotel. No te pierdas esta aventura inolvidable por las fascinantes islas de la <span style=\"color: #19dd19;\">Bah\u00eda de Phang Nga<\/span> y m\u00e1s all\u00e1.<\/span><\/li>\n<li style=\"text-align: center;\"><span style=\"font-size: medium;\">Nuestro tour temprano garantiza la mejor experiencia del d\u00eda, para que puedas disfrutar cada momento al m\u00e1ximo.<\/span><\/li>\n<li style=\"text-align: center;\"><span style=\"font-size: medium;\">Regreso a <span style=\"color: #19dd19;\">Royal Phuket Marina<\/span> alrededor de las <span style=\"color: #19dd19;\">15:00 \/ 15:15 PM.<\/span><\/span>\n<p style=\"text-align: center;\">\n<\/li>\n<\/ul>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb13px|||||\u00bb custom_padding=\u00bb8px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb21px||13px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/77.jpg\u00bb title_text=\u00bb77&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/76.jpg\u00bb title_text=\u00bb76&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/78.jpg\u00bb title_text=\u00bb78&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb7px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb15px\u00bb global_colors_info=\u00bb{}\u00bb]\n<p><span style=\"color: #00ff00;\"><strong>Embarcaci\u00f3n del Tour:<\/strong><\/span><\/p>\n<p>La excursi\u00f3n se realiza a bordo de un<span style=\"color: #00ff00;\"> <strong>speed boat<\/strong> <\/span>de alta capacidad, equipado con<span style=\"color: #00ff00;\"> <strong>tres motores<\/strong> <\/span>para asegurar un viaje r\u00e1pido, c\u00f3modo y seguro. Su dise\u00f1o moderno y robusto garantiza la estabilidad y el confort, permiti\u00e9ndote disfrutar de la experiencia con total tranquilidad. \u00a1Prep\u00e1rate para un paseo \u00fanico por las aguas de la Bah\u00eda de Phang Nga!<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px||9px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb19275&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb auto=\u00bbon\u00bb auto_speed=\u00bb2000&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb19276&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb auto=\u00bbon\u00bb auto_speed=\u00bb2000&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb19277&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb auto=\u00bbon\u00bb auto_speed=\u00bb2000&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb15px\u00bb global_colors_info=\u00bb{}\u00bb]\n<p><span style=\"color: #00ff00;\"><strong>Garant\u00eda de Calidad en el Tour de la Bah\u00eda de Phang Nga con Panda Phuket Tour<\/strong><\/span><\/p>\n<p>Al contratar el <span style=\"color: #00ff00;\"><strong>Tour de la Bah\u00eda de Phang Nga<\/strong> <\/span>con <span style=\"color: #00ff00;\"><strong>Panda Phuket Tour<\/strong><\/span>, te aseguramos una experiencia de calidad excepcional. Nos comprometemos a ofrecerte un servicio personalizado, con gu\u00edas expertos y embarcaciones seguras y c\u00f3modas, para que disfrutes al m\u00e1ximo de esta maravilla natural. Con nuestra atenci\u00f3n al detalle, podr\u00e1s explorar la bah\u00eda en un ambiente tranquilo y sin preocupaciones, sabiendo que tu seguridad y satisfacci\u00f3n son nuestra prioridad. \u00a1Conf\u00eda en nosotros para vivir una experiencia inolvidable en uno de los destinos m\u00e1s ic\u00f3nicos de Tailandia!<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-Beyond-Background-2.jpg\u00bb title_text=\u00bbJames Bond Beyond Background 2&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb7px||3px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb17px\u00bb custom_margin=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]\n<p><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">*El programa esta sujeto a cambios en el nivel del mar, condiciones meteorol\u00f3gicas o cambios por orden del parque nacional, pero no te preocupes, en el programa no hay un orden estipulado y nos vamos adaptando para disfrutar al m\u00e1ximo, el gu\u00eda explicar\u00e1 todo los detalles y cualquier duda tambi\u00e9n se podr\u00e1 preguntar al gu\u00eda durante el tour. Cualquier cambio ser\u00e1 por seguridad o por mejorar la experiencia.<\/span><\/p>\n<p><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">*Tour no recomendado para mujeres embarazadas \ud83e\udd30\ud83c\udffc o menores de 1 a\u00f1o\ud83d\udc7c<\/span><\/p>\n<div class=\"et_pb_text_inner\">\n<div class=\"et-fb-popover-tinymce\" data-shortcode-id=\"4.5.0.0-1707800124601\" data-quickaccess-editable=\"yes\">\u00a0<\/div>\n<\/div>\n[\/et_pb_text][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb inline_fonts=\u00bbAlata\u00bb global_colors_info=\u00bb{}\u00bb]\n<h2><span style=\"color: #19dd19;\"><strong><span style=\"font-family: Alata; font-size: medium;\"><a style=\"color: #19dd19;\">\u00bfQu\u00e9 incluye?<\/a><\/span><\/strong><\/span><\/h2>\n<ul>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">El tour incluye desplazamiento y entrega en su hotel, en cualquier hotel de Phuket.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Lancha motora.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Paseo en canoa con un gu\u00eda.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Desayuno light, almuerzo y agua.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Seguro de accidentes durante el tour.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Tasas parque nacional.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Gu\u00eda multiling\u00fce en espa\u00f1ol.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: center;\"><span style=\"font-family: Alata; font-weight: normal; font-size: small; color: #19dd19;\"><strong>PARA VER EL PRECIO RESERVANDO HOY, ELIGE EL D\u00cdA QUE QUIERES REALIZAR LA ACTIVIDAD Y EL N\u00daMERO DE PERSONAS.\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: Alata; font-weight: normal; font-size: small; color: #19dd19;\"><strong>SI RESERVAS CON ANTELACI\u00d3N OBTENDR\u00c1S UN DESCUENTO AUTOM\u00c1TICO<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: Alata; font-weight: normal; font-size: small; color: #19dd19;\"><strong>ASEGURA TU RESERVA AL MEJOR PRECIO, PLAZAS LIMITADAS<\/strong><\/span><\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb23px||8px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb|auto||7px||\u00bb custom_padding=\u00bb8px||27px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAnton||||||||\u00bb text_font_size=\u00bb13px\u00bb text_letter_spacing=\u00bb5px\u00bb global_colors_info=\u00bb{}\u00bb]\n<p>TRAVEL PRODUCT ID: 1-1011<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb|-40px||6px||\u00bb custom_padding=\u00bb0px||4px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAnton||||||||\u00bb text_text_color=\u00bb#ea7d00&#8243; text_font_size=\u00bb41px\u00bb text_line_height=\u00bb1em\u00bb header_font=\u00bbAnton|||on|||||\u00bb header_text_color=\u00bb#0cd3d3&#8243; header_font_size=\u00bb41px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.4em\u00bb custom_margin=\u00bb|-222px||||\u00bb header_text_shadow_style=\u00bbpreset1&#8243; header_text_shadow_vertical_length=\u00bb0.03em\u00bb header_text_shadow_blur_strength=\u00bb0.06em\u00bb header_text_shadow_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]\n<h1><span style=\"color: #19dd19;\">James Bond and Beyond Phang Nga Bay EN GRUPO &#8211; SALIDA TEMPRANA EN ESPA\u00d1OL (M\u00e1ximo 32 personas)<\/span><\/h1>\n<h2>El Mirador de Samet: Exclusivo en la Salida Temprana<\/h2>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-Beyond-Background.jpg\u00bb title_text=\u00bbJames Bond Beyond Background\u00bb disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/Canoeing-en-Phang-Nga-Desde-Phuket-Background-jpg.webp\u00bb custom_padding=\u00bb21px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||7px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb15px\u00bb text_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb|-87px||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\" style=\"text-align: left;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\"><span style=\"font-size: x-large;\"><strong>Pick Up Time<\/strong><\/span><\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\" style=\"text-align: left;\"><span style=\"color: #179bbd; font-family: Alata; font-size: medium;\"><span style=\"color: #28b56e;\"><strong><span style=\"color: #808080;\"><span style=\"color: #e84c09;\">\u23f1<\/span><\/span><\/strong><\/span><\/span><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">05:00-06:00 AM:<\/span> Te recogeremos en tu hotel y te llevaremos al <span style=\"color: #19dd19;\">Royal Phuket Marina.<\/span><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: medium;\"><span style=\"color: #179bbd; font-family: Alata; font-size: medium;\"><span style=\"color: #28b56e;\"><strong><span style=\"color: #808080;\"><span style=\"color: #e84c09;\">\u23f1<\/span><\/span><\/strong><\/span><\/span><span style=\"color: #19dd19;\">06:40-07:00 AM: <\/span>Salida temprana hacia la <span style=\"color: #19dd19;\">Bah\u00eda de Phang Nga.<\/span> Rel\u00e1jate en nuestro c\u00f3modo speedboat mientras nos embarcamos en nuestra aventura para explorar las fascinantes islas y lugares de inter\u00e9s.<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-justify para-style-body\" style=\"text-align: left;\">[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||10px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAnton||||||||\u00bb text_text_color=\u00bb#f7d200&#8243; text_font_size=\u00bb37px\u00bb text_letter_spacing=\u00bb8px\u00bb text_line_height=\u00bb1em\u00bb text_text_shadow_style=\u00bbpreset1&#8243; text_text_shadow_vertical_length=\u00bb0.03em\u00bb text_text_shadow_blur_strength=\u00bb0.06em\u00bb text_text_shadow_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]\n<p><span style=\"color: #19dd19;\">\u00a0 \u00a0 \u00a0PHANG NGA BAY<\/span><\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-007-en-Tailandia-Background-jpg.webp\u00bb custom_padding=\u00bb21px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb15px\u00bb custom_margin=\u00bb|-85px||||\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<p style=\"text-align: left;\"><span style=\"font-size: medium;\">Emb\u00e1rcate en una aventura inolvidable mientras exploramos la ic\u00f3nica <span style=\"color: #19dd19;\">Isla James Bond<\/span> y sus hermosos alrededores. Desde visitar la famosa isla destacada en <span style=\"color: #19dd19;\">\u00ab007 El hombre de la pistola de oro\u00bb<\/span> hasta remar en canoa a trav\u00e9s de manglares y cuevas, este tour de madrugada est\u00e1 repleto de actividades emocionantes y paisajes impresionantes. Experimenta la belleza impresionante de la <span style=\"color: #19dd19;\">Bah\u00eda de Phang Nga<\/span> y sus cautivadoras islas en este emocionante viaje.<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">*ITINERARIO:<\/span> *Nos reservamos el derecho de modificar o alterar la ruta planificada seg\u00fan fluctuaciones en patrones clim\u00e1ticos, variaciones de mareas, condiciones oce\u00e1nicas o cualquier situaci\u00f3n impredecible.<\/span><\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/Canoeing-en-Thum-Lod-Desde-Phuket-Background-jpg.webp\u00bb custom_padding=\u00bb2px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px||4px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb custom_margin=\u00bb|-170px||-3px||\u00bb global_colors_info=\u00bb{}\u00bb]\n<ul>\n<li>\n<p style=\"text-align: left;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">KOH PANAK<\/span> Visita desde el barco Koh Panak, una isla impresionante con caracter\u00edsticas geol\u00f3gicas \u00fanicas. Explora el cautivador paisaje de la isla y marav\u00edllate con su belleza natural. <\/span><\/p>\n<\/li>\n<li>\n<p style=\"text-align: left;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">TOUR POR LA CUEVA A PIE<\/span> Luego, emprenderemos un tour a pie por cuevas. Ad\u00e9ntrate en las profundidades de estas cuevas encantadas y sorpr\u00e9ndete con las formaciones incre\u00edbles que hay dentro.<\/span><\/p>\n<\/li>\n<li><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">ISLA JAMES BOND<\/span> Luego visitaremos la famosa Isla James Bond, el lugar de rodaje de <span style=\"color: #19dd19;\">\u00ab007 El hombre de la pistola de oro\u00bb.<\/span> Explora la ic\u00f3nica isla y toma fotos inolvidables con los distintivos acantilados de piedra caliza y formaciones rocosas.<\/span><\/li>\n<li><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">CANOA EN TUM LOD<\/span> Vive una relajante aventura en canoa a trav\u00e9s de los manglares y cuevas de <span style=\"color: #19dd19;\">Tum Lod.<\/span> Rema en las serenas aguas y contempla la impresionante belleza natural que te rodea.<\/span><span style=\"font-size: medium;\"><\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/Panyee-Village-Flotante-en-Phang-Nga-Background-jpg.webp\u00bb custom_padding=\u00bb2px||14px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb custom_margin=\u00bb|-100px||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<ul>\n<li>\n<p style=\"text-align: left;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">KOH PANYEE DESDE EL BARCO<\/span> Mientras continuamos nuestro recorrido, pasaremos por la zona del restaurante frontal de<span style=\"color: #19dd19;\"> Koh Panyee<\/span>, un pueblo flotante \u00fanico construido sobre pilotes sobre el agua. Disfruta del avistamiento desde el barco y contempla la fascinante arquitectura de este notable pueblo.<\/span><\/p>\n<\/li>\n<li style=\"text-align: left;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">PASEO POR KOH PANYEE EN EL PUEBLO FLOTANTE<\/span> Visita <span style=\"color: #19dd19;\">Koh Panyee<\/span> y camina por el pueblo flotante, donde podr\u00e1s explorar el estilo de vida local y vivir la vibrante cultura.<\/span><\/li>\n<li>\n<p style=\"text-align: left;\"><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">ALMUERZO BUFFET TAILAND\u00c9S EN LA ISLA<\/span> Disfruta de un delicioso almuerzo en un restaurante local en la isla de Panyee (New Fern). Saborea aut\u00e9nticos sabores locales mientras contemplas las impresionantes vistas de la isla.<\/span><\/p>\n<\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/Phang-Nga-Bay-Desde-Phuket-Background-jpg.webp\u00bb custom_padding=\u00bb2px||14px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb custom_margin=\u00bb|-81px||||\u00bb global_colors_info=\u00bb{}\u00bb]\n<ul style=\"text-align: left;\">\n<li style=\"list-style-type: none;\">\n<ul>\n<li><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">VISTA DE LA BAH\u00cdA DE PHANG NGA NUEVO!!!<\/span> Disfruta de la vista desde el punto de vista de <span style=\"color: #19dd19;\">Samet Nangshe.<\/span><\/span><\/li>\n<li><span style=\"font-size: medium;\"><span style=\"color: #19dd19;\">REL\u00c1JATE Y TOMA EL SOL EN UNA PLAYA TROPICAL<\/span> Termina el d\u00eda relaj\u00e1ndote y tomando el sol en una playa tropical, sum\u00e9rgete en la suave arena rodeada de aguas esmeralda. Luego regresaremos al Royal Phuket Marina para tu traslado de vuelta al hotel. No te pierdas esta aventura inolvidable por las fascinantes islas de la <span style=\"color: #19dd19;\">Bah\u00eda de Phang Nga<\/span> y m\u00e1s all\u00e1.<\/span><\/li>\n<li><span style=\"font-size: medium;\">Nuestro tour temprano garantiza la mejor experiencia del d\u00eda, para que puedas disfrutar cada momento al m\u00e1ximo.<\/span><\/li>\n<li><span style=\"font-size: medium;\">Regreso a <span style=\"color: #19dd19;\">Royal Phuket Marina<\/span> alrededor de las <span style=\"color: #19dd19;\">15:00 \/ 15:15 PM.<\/span><\/span>\n<p style=\"text-align: center;\">\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px||5px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb17px\u00bb custom_margin=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]\n<p><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">*El programa esta sujeto a cambios en el nivel del mar, condiciones meteorol\u00f3gicas o cambios por orden del parque nacional, pero no te preocupes, en el programa no hay un orden estipulado y nos vamos adaptando para disfrutar al m\u00e1ximo, el gu\u00eda explicar\u00e1 todo los detalles y cualquier duda tambi\u00e9n se podr\u00e1 preguntar al gu\u00eda durante el tour. Cualquier cambio ser\u00e1 por seguridad o por mejorar la experiencia.<\/span><\/p>\n<p><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">*Tour no recomendado para mujeres embarazadas \ud83e\udd30\ud83c\udffc o menores de 1 a\u00f1o\ud83d\udc7c<\/span><\/p>\n<div class=\"et_pb_text_inner\">\n<div class=\"et-fb-popover-tinymce\" data-shortcode-id=\"4.5.0.0-1707800124601\" data-quickaccess-editable=\"yes\">\u00a0<\/div>\n<\/div>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb13px|||||\u00bb custom_padding=\u00bb8px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb21px||13px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/77.jpg\u00bb title_text=\u00bb77&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/76.jpg\u00bb title_text=\u00bb76&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/78.jpg\u00bb title_text=\u00bb78&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb7px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb15px\u00bb global_colors_info=\u00bb{}\u00bb]\n<p><span style=\"color: #00ff00;\"><strong>Embarcaci\u00f3n del Tour:<\/strong><\/span><\/p>\n<p>La excursi\u00f3n se realiza a bordo de un<span style=\"color: #00ff00;\"> <strong>speed boat<\/strong> <\/span>de alta capacidad, equipado con<span style=\"color: #00ff00;\"> <strong>tres motores<\/strong> <\/span>para asegurar un viaje r\u00e1pido, c\u00f3modo y seguro. Su dise\u00f1o moderno y robusto garantiza la estabilidad y el confort, permiti\u00e9ndote disfrutar de la experiencia con total tranquilidad. \u00a1Prep\u00e1rate para un paseo \u00fanico por las aguas de la Bah\u00eda de Phang Nga!<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px||9px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb19275&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb auto=\u00bbon\u00bb auto_speed=\u00bb2000&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb19276&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb auto=\u00bbon\u00bb auto_speed=\u00bb2000&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb19277&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb auto=\u00bbon\u00bb auto_speed=\u00bb2000&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb text_font_size=\u00bb15px\u00bb global_colors_info=\u00bb{}\u00bb]\n<p><span style=\"color: #00ff00;\"><strong>Garant\u00eda de Calidad en el Tour de la Bah\u00eda de Phang Nga con Panda Phuket Tour<\/strong><\/span><\/p>\n<p>Al contratar el <span style=\"color: #00ff00;\"><strong>Tour de la Bah\u00eda de Phang Nga<\/strong> <\/span>con <span style=\"color: #00ff00;\"><strong>Panda Phuket Tour<\/strong><\/span>, te aseguramos una experiencia de calidad excepcional. Nos comprometemos a ofrecerte un servicio personalizado, con gu\u00edas expertos y embarcaciones seguras y c\u00f3modas, para que disfrutes al m\u00e1ximo de esta maravilla natural. Con nuestra atenci\u00f3n al detalle, podr\u00e1s explorar la bah\u00eda en un ambiente tranquilo y sin preocupaciones, sabiendo que tu seguridad y satisfacci\u00f3n son nuestra prioridad. \u00a1Conf\u00eda en nosotros para vivir una experiencia inolvidable en uno de los destinos m\u00e1s ic\u00f3nicos de Tailandia!<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-Beyond-Background-2.jpg\u00bb title_text=\u00bbJames Bond Beyond Background 2&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px||5px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbAlata||||||||\u00bb inline_fonts=\u00bbAlata\u00bb global_colors_info=\u00bb{}\u00bb]\n<h2><span style=\"color: #19dd19;\"><strong><span style=\"font-family: Alata; font-size: medium;\"><a style=\"color: #19dd19;\">\u00bfQu\u00e9 incluye?<\/a><\/span><\/strong><\/span><\/h2>\n<ul>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">El tour incluye desplazamiento y entrega en su hotel, en cualquier hotel de Phuket.\u00a0<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Lancha motora<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Paseo en canoa con un gu\u00eda.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Desayuno light, almuerzo y agua.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Seguro de accidentes durante el tour.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Tasas parque nacional.<\/span><\/li>\n<li><span style=\"font-family: Alata; font-weight: normal; font-size: medium;\">Gu\u00eda multiling\u00fce en espa\u00f1ol.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: center;\"><span style=\"font-family: Alata; font-weight: normal; font-size: small; color: #19dd19;\"><strong>PARA VER EL PRECIO RESERVANDO HOY, ELIGE EL D\u00cdA QUE QUIERES REALIZAR LA ACTIVIDAD Y EL N\u00daMERO DE PERSONAS.\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: Alata; font-weight: normal; font-size: small; color: #19dd19;\"><strong>SI RESERVAS CON ANTELACI\u00d3N OBTENDR\u00c1S UN DESCUENTO AUTOM\u00c1TICO<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: Alata; font-weight: normal; font-size: small; color: #19dd19;\"><strong>ASEGURA TU RESERVA AL MEJOR PRECIO, PLAZAS LIMITADAS<\/strong><\/span><\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px||5px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2023\/08\/ISLA-JAMES-BOND-PHANG-NGA-7.jpg\u00bb alt=\u00bbjames bond\u00bb title_text=\u00bbISLA JAMES BOND PHANG NGA 7&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2023\/08\/ISLA-JAMES-BOND-PHANG-NGA-8.jpg\u00bb alt=\u00bbPhang Nga\u00bb title_text=\u00bbISLA JAMES BOND PHANG NGA 8&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-and-Beyond-jpg.webp\u00bb title_text=\u00bbJames Bond and Beyond\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-and-Beyond-4-jpg.webp\u00bb title_text=\u00bbJames Bond and Beyond 4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-and-Beyond-3-jpg.webp\u00bb title_text=\u00bbJames Bond and Beyond 3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-and-Beyond-5-jpg.webp\u00bb title_text=\u00bbJames Bond and Beyond 5&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2018\/07\/James-Bond-and-Beyond-2-jpg.webp\u00bb title_text=\u00bbJames Bond and Beyond 2&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/pandaphukettour.com\/wp-content\/uploads\/2019\/11\/24.jpg\u00bb alt=\u00bbpoblado flotante\u00bb title_text=\u00bbpoblado flotante\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb12346,12347,12349,14292,14290,14289,14288,14291&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb auto=\u00bbon\u00bb auto_speed=\u00bb2000&#8243; box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.23.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]\n<div class=\"turia-booking\" data-service=\"P11\" data-lang=\"es\"  data-embed=\"box\"><\/div>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb5px||17px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb6px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb18px\u00bb custom_padding=\u00bb|||21px||\u00bb box_shadow_style=\u00bbpreset5&#8243; box_shadow_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{}\u00bb]\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/pandaphukettour.com\/james-bond-big-boat-en-barco\/\">\u00bfQUIERES UNA OPCI\u00d3N M\u00c1S ECON\u00d3MICA? Visita este link<\/a><\/p>\n<p>&nbsp;<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-6px|||||\u00bb custom_padding=\u00bb4px||10px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_post_nav _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_post_nav][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>TRAVEL PRODUCT ID: 1 &#8211; 1011James Bond and Beyond Phang Nga Bay EN GRUPO &#8211; SALIDA TEMPRANA EN ESPA\u00d1OL (M\u00e1ximo 32 personas)El Mirador de Samet: Exclusivo en la Salida TempranaPICK UP TIME \u23f105:00-06:00 AM: Te recogeremos en tu hotel y te llevaremos al Royal Phuket Marina. \u23f106:40-07:00 AM: Salida temprana hacia la Bah\u00eda de Phang&hellip;<\/p>","protected":false},"author":1,"featured_media":14292,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[277,4,308,8,167,278],"tags":[149,14,13,150],"class_list":["post-556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-excursiones-en-espanol","category-excursionesphuket","category-excursiones-para-cruceros-phuket","category-islas","category-excursiones-james-bond-desde-phuket","category-phuket-en-2-dias","tag-contratar-excursiones-phuket","tag-excursiones-en-espanol-tailandia","tag-excursiones-en-phuket","tag-reservar-excursiones-phuket"],"_links":{"self":[{"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/posts\/556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/comments?post=556"}],"version-history":[{"count":0,"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/posts\/556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/media\/14292"}],"wp:attachment":[{"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/media?parent=556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/categories?post=556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pandaphukettour.com\/it\/wp-json\/wp\/v2\/tags?post=556"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}